{"id":189985,"date":"2018-07-31T12:00:51","date_gmt":"2018-07-31T16:00:51","guid":{"rendered":"https:\/\/relaismontroyal.org\/wp\/?p=189985"},"modified":"2018-07-29T20:45:14","modified_gmt":"2018-07-30T00:45:14","slug":"evangile-du-dimanche-5-aout-2018","status":"publish","type":"post","link":"https:\/\/relaismontroyal.org\/wp\/evangile-du-dimanche-5-aout-2018\/","title":{"rendered":"\u00c9vangile du dimanche 5 ao\u00fbt 2018"},"content":{"rendered":"<h3>18e dimanche ordinaire\u00a0(ann\u00e9e B), selon l&rsquo;\u00e9crit de Jean\u00a06, 24-35<\/h3>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/i0.wp.com\/relaismontroyal.org\/wp\/wp-content\/uploads\/2014\/02\/IMG_5175-150x150.jpg?resize=150%2C150\" alt=\"Du pain sur la table\" width=\"150\" height=\"150\" \/>24<\/span> Quand la foule voit que J\u00e9sus n&rsquo;est pas l\u00e0, ni ses disciples,<br \/>\nils montent dans les barques et vont \u00e0 Capharna\u00fcm chercher J\u00e9sus.<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\">25<\/span> L&rsquo;ayant trouv\u00e9 de l&rsquo;autre c\u00f4t\u00e9 de la mer, ils lui disent:<br \/>\nRabbi, quand es-tu venu ici?<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\">26<\/span> J\u00e9sus leur r\u00e9pond: Amen! Amen! je vous le dis:<br \/>\nvous me cherchez, non pas parce que vous avez vu des \u00ab\u00a0signes\u00a0\u00bb<br \/>\nmais parce que vous avez mang\u00e9 des pains et avez \u00e9t\u00e9 rassasi\u00e9s.<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\">27<\/span> Agissez, non pour la nourriture p\u00e9rissable<br \/>\nmais pour celle qui demeure en vie \u00e9ternelle,<br \/>\ncelle que le Fils de l&rsquo;homme vous donnera,<br \/>\ncar c&rsquo;est lui que le P\u00e8re, que Dieu a marqu\u00e9 du sceau.<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\">28<\/span> Ils lui disent alors:<br \/>\nQue devons-nous faire pour accomplir les actions de Dieu?<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\">29<\/span> J\u00e9sus leur r\u00e9pond:<br \/>\nVoici l&rsquo;action de Dieu: croire en celui-l\u00e0 qu&rsquo;Il a envoy\u00e9.<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\">30<\/span> Ils lui disent:<br \/>\nQuel signe fais-tu, toi, pour que nous voyions et croyions en toi?<br \/>\nQu&rsquo;est-ce que tu accomplis?<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\">31<\/span> Nos anc\u00eatres ont mang\u00e9 la manne dans le d\u00e9sert, selon ce qui est \u00e9crit:<br \/>\n\u00abIl leur a donn\u00e9 \u00e0 manger le pain venant du ciel.\u00bb<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\">32<\/span> J\u00e9sus leur dit: Amen! Amen! Je vous le dis:<br \/>\nce n&rsquo;est pas Mo\u00efse qui vous a donn\u00e9 le pain venant du ciel<br \/>\nmais c&rsquo;est mon P\u00e8re qui vous donne le pain venant du ciel, le v\u00e9ritable.<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\">33<\/span> Car celui qui descend du ciel et donne vie au monde est le pain de Dieu.<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\">34<\/span> Ils lui disent alors:<br \/>\nSeigneur, donne-nous toujours de ce pain.<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ff9900;\">35<\/span> J\u00e9sus leur dit:<br \/>\nMoi, je suis le pain de la vie.<br \/>\nCelui qui vient \u00e0 moi n&rsquo;aura plus faim,<br \/>\ncelui qui croit en moi n&rsquo;aura plus soif, jamais.<\/p>\n<p>&#8212;<\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/info-christianisme.org\/wp\/wp-content\/uploads\/2014\/01\/18ordinaireB.pdf\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/i0.wp.com\/relaismontroyal.org\/wp\/wp-content\/uploads\/2014\/02\/pdf-icon-150x150.png?resize=150%2C150\" alt=\"Fichier .pdf\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h3 style=\"text-align: left;\" align=\"right\">Le commentaire\u00a0<a href=\"http:\/\/info-christianisme.org\/wp\/wp-content\/uploads\/2014\/01\/17ordinaireB.pdf\" target=\"_blank\" rel=\"noopener\">du pain sur la table<\/a>,<\/h3>\n<h6 style=\"text-align: left;\" align=\"right\">par Georges Convert.<\/h6>\n<p><span style=\"font-size: small;\">Nous voici au seuil d&rsquo;un grand d\u00e9bat entre la foule et J\u00e9sus.<br \/>\nUn d\u00e9bat qui d\u00e9bordera le cadre de la synagogue de Capharna\u00fcm<br \/>\no\u00f9 il a commenc\u00e9 pour se poursuivre tout au long des si\u00e8cles entre Juifs et chr\u00e9tiens:<br \/>\nQuel signe fais-tu pour que nous croyions en toi?<\/span><\/p>\n<p><strong>La place du texte dans le r\u00e9cit de Jean<\/strong><br \/>\nNous sommes dans la synagogue de Capharna\u00fcm <span style=\"font-size: small;\">(<strong>6<\/strong>,59)<\/span>,<br \/>\no\u00f9 la foule a rejoint J\u00e9sus apr\u00e8s le signe des pains multipli\u00e9s.<br \/>\nTout le chapitre <span style=\"font-size: small;\"><strong>6<\/strong><\/span> sera consacr\u00e9 \u00e0 donn\u00e9 le sens de ce repas de pain,<br \/>\ncomme le chapitre <span style=\"font-size: small;\"><strong>4<\/strong><\/span> nous avait parl\u00e9 de l&rsquo;eau de la vie \u00e9ternelle<br \/>\nlors de la rencontre entre J\u00e9sus et une femme de Samarie aupr\u00e8s du puits.<br \/>\nLe repas des pains multipli\u00e9s a soulev\u00e9 l&rsquo;enthousiasme de la foule<br \/>\nau point qu&rsquo;elle voudrait forcer J\u00e9sus \u00e0 prendre la t\u00eate du pays comme messie:<br \/>\n<span style=\"color: #0000ff;\"><em>Celui-ci est vraiment le Proph\u00e8te qui doit venir dans le monde.<\/em><\/span><br \/>\nMais, dans le contexte d&rsquo;un Isra\u00ebl occup\u00e9 par les Romains depuis pr\u00e8s de 100 ans,<br \/>\nconsentir \u00e0 se d\u00e9clarer messie serait un acte de suicide.<br \/>\nLes Romains arr\u00eateront J\u00e9sus et le condamneront \u00e0 mort.<br \/>\nBien plus, et surtout, ce serait entra\u00eener J\u00e9sus sur un chemin politique,<br \/>\nchemin qu&rsquo;il a refus\u00e9 d\u00e8s le d\u00e9part de sa mission,<br \/>\ncomme en t\u00e9moigne le r\u00e9cit des tentations <span style=\"font-size: small;\">(cf. Mt <strong>4<\/strong>,1-11)<\/span>.<br \/>\nC&rsquo;est pourquoi J\u00e9sus s&rsquo;est retir\u00e9 seul dans la montagne<br \/>\npendant que ses disciples regagnaient Capharna\u00fcm, la ville de Simon-Pierre,<br \/>\ncette ville o\u00f9 J\u00e9sus revient apr\u00e8s chaque mission.<br \/>\nNotre passage n&rsquo;est que le pr\u00e9ambule de la discussion entre les Juifs et J\u00e9sus,<br \/>\nune discussion qui doit d\u00e9voiler le sens du repas des pains multipli\u00e9s<br \/>\net faire comprendre le r\u00f4le v\u00e9ritable que J\u00e9sus y joue.<\/p>\n<p><span style=\"color: #0000ff;\"><em><strong>Pourquoi me cherchez-vous?<\/strong><\/em><\/span><br \/>\nJ\u00e9sus, d&#8217;embl\u00e9e, veut dissiper l&rsquo;ambigu\u00eft\u00e9:<br \/>\n<span style=\"color: #0000ff;\"><em>Vous ne me cherchez pas parce que vous avez vu un signe,<br \/>\nmais parce que vous avez mang\u00e9 \u00e0 \u00eatre rassasi\u00e9s.<\/em><\/span><br \/>\nQu&rsquo;est ce que \u00abvoir un signe\u00bb?<br \/>\nUn signe, c&rsquo;est un geste, un objet qui fait comprendre une autre r\u00e9alit\u00e9,<br \/>\nqui \u00ab\u00a0fait signe\u00a0\u00bb en renvoyant \u00e0 cette r\u00e9alit\u00e9 souvent invisible.<br \/>\nC&rsquo;est un geste \u00ab\u00a0signifiant\u00a0\u00bb, qui d\u00e9voile un sens plus profond.<br \/>\nAinsi le bouquet de fleurs que l&rsquo;amant offre \u00e0 son aim\u00e9e \u00ab\u00a0signifie\u00a0\u00bb son amour.<br \/>\nLe reproche de J\u00e9sus \u00e0 ses auditeurs est<br \/>\ndonc de ne pas avoir perc\u00e9 le sens profond du geste du repas.<br \/>\nNon que les gens n&rsquo;aient pas vu le signe.<br \/>\nIls ont bien per\u00e7u le repas comme l&rsquo;\u00e9v\u00e9nement qui marque l&rsquo;av\u00e8nement du Proph\u00e8te:<br \/>\nle Proph\u00e8te qui serait semblable \u00e0 Mo\u00efse, tel que le d\u00e9crivait le Deut\u00e9ronome <span style=\"font-size: small;\">(<strong>18<\/strong>,15)<\/span>:<br \/>\n<span style=\"color: #0000ff;\"><em>C&rsquo;est un proph\u00e8te comme moi que Dieu vous suscitera: c&rsquo;est lui que vous \u00e9couterez.<\/em><\/span><br \/>\nCe proph\u00e8te \u00e9tait souvent identifi\u00e9 comme le messie attendu, esp\u00e9r\u00e9.<br \/>\nIl interpr\u00e9terait avec autorit\u00e9 la <em>Tora<\/em><br \/>\n-dont les interpr\u00e9tations faites par les scribes et les rabbis \u00e9taient multiples-<br \/>\net il lib\u00e9rerait le peuple du joug des Romains qui occupaient le pays.<br \/>\nIl serait vraiment comme Mo\u00efse qui avait donn\u00e9 la <em>Tora<\/em><br \/>\net qui avait lib\u00e9r\u00e9 les tribus r\u00e9duites en esclavage en \u00c9gypte.<br \/>\nDe la m\u00eame fa\u00e7on que Mo\u00efse avait donn\u00e9 la manne,<br \/>\nainsi J\u00e9sus donnait le pain comme un nouveau Mo\u00efse.<br \/>\nMais de quel pain s&rsquo;agissait-il pour J\u00e9sus?<br \/>\n<span style=\"color: #0000ff;\"><em>Agissez, non pour la nourriture p\u00e9rissable mais pour celle qui demeure en vie \u00e9ternelle&#8230;<\/em><\/span><br \/>\nCe repas des pains multipli\u00e9s voulait \u00eatre le signe d&rsquo;une nourriture qui ne p\u00e9rit pas.<br \/>\nPourquoi et comment les auditeurs de J\u00e9sus auraient-ils d\u00fb saisir ce signe?<br \/>\nPour le comprendre, il nous faut rappeler le signe de la manne.<\/p>\n<p><strong>Le signe de la manne<\/strong><br \/>\nLorsque les tribus juives se trouvaient en route vers la Palestine depuis l&rsquo;\u00c9gypte,<br \/>\nelles se sont trouv\u00e9es souvent affam\u00e9es dans les r\u00e9gions d\u00e9sertiques qu&rsquo;elles traversaient.<br \/>\nEt elles ont surv\u00e9cu gr\u00e2ce \u00e0 la manne.<br \/>\nCe mot d\u00e9signe les granul\u00e9s \u00e0 saveur de miel<br \/>\nqui tombent de certains arbrisseaux piqu\u00e9s par un insecte.<br \/>\nCes granul\u00e9s ne se conservent pas longtemps car ils fondent rapidement \u00e0 la chaleur du jour.<br \/>\nRecueillis sans avoir \u00e9t\u00e9 cultiv\u00e9s, ils sont per\u00e7us comme un don de Dieu.<br \/>\nLa manne sera donc surnomm\u00e9e le \u00ab\u00a0pain du ciel\u00a0\u00bb,<br \/>\ncomme il est dit dans le psaume <span style=\"font-size: small;\"><strong>78<\/strong> (24-25)<\/span>:<br \/>\n<span style=\"color: #0000ff;\"><em>Pour les nourrir [Dieu] fit pleuvoir la manne; il leur donna le pain des cieux.<br \/>\nChacun mangea le pain des Forts, il leur envoya des vivres \u00e0 sati\u00e9t\u00e9.<\/em><\/span><br \/>\nDiverses croyances, attest\u00e9es du temps de J\u00e9sus, disaient<br \/>\nque la manne reviendrait avec la venue du messie.<br \/>\nAinsi s&rsquo;exprime l&rsquo;Apocalypse de Baruch:<br \/>\n<span style=\"color: #990099;\">\u00abEn ce m\u00eame temps, il adviendra que le tr\u00e9sor de la manne descendra de nouveau d&rsquo;en haut<br \/>\net ils en mangeront en ces ann\u00e9es-l\u00e0\u00bb<\/span> <span style=\"font-size: small;\">(II Baruch, XXIX,8)<\/span>.<br \/>\nCes ann\u00e9es-l\u00e0 sont celles de la venue du messie.<br \/>\nAinsi, dans le repas des pains multipli\u00e9s, la foule pouvait bien voir le signe de la venue du messie.<br \/>\nEt elle pouvait s&rsquo;attendre (conform\u00e9ment \u00e0 ces \u00e9crits)<br \/>\n\u00e0 ce que ce signe de multiplication de la nourriture se renouvelle.<br \/>\nC&rsquo;est peut-\u00eatre la raison de cette nouvelle demande:<br \/>\n<span style=\"color: #0000ff;\"><em>Quel signe fais-tu, toi, pour que nous voyions et croyions en toi?<br \/>\nQu&rsquo;est-ce que tu accomplis?<br \/>\nNos anc\u00eatres ont mang\u00e9 la manne dans le d\u00e9sert, selon ce qui est \u00e9crit:<br \/>\n\u00abIl leur a donn\u00e9 \u00e0 manger le pain venant du ciel.\u00bb<\/em><\/span><br \/>\nMais d\u00e9j\u00e0 la r\u00e9flexion biblique avait orient\u00e9 les esprits vers une autre nourriture.<br \/>\nSe nourrir est toujours une exp\u00e9rience de d\u00e9pendance:<br \/>\nnous sommes tributaires de la cr\u00e9ation pour survivre.<br \/>\nNous avons un besoin essentiel d&rsquo;eau, d&rsquo;air, de v\u00e9g\u00e9taux&#8230;<br \/>\nCette d\u00e9pendance \u00ab\u00a0signifie\u00a0\u00bb notre \u00e9tat de cr\u00e9ature, d&rsquo;\u00eatre d\u00e9pendant du Cr\u00e9ateur.<br \/>\nC&rsquo;est la conscience de cette d\u00e9pendance qui s&rsquo;exprime dans la pri\u00e8re<br \/>\nqui est faite au d\u00e9but ou \u00e0 la fin d&rsquo;un repas: b\u00e9n\u00e9dicite ou gr\u00e2ces.<br \/>\nElle dit notre reconnaissance au Cr\u00e9ateur qui nous donne la vie.<br \/>\nCette d\u00e9pendance pour nourrir le corps oriente vers une r\u00e9alit\u00e9 plus profonde.<br \/>\nLa d\u00e9pendance pour nourrir notre \u00eatre corporel conduit \u00e0 la d\u00e9pendance<br \/>\npour nourrir notre \u00eatre spirituel: Qui suis-je? D&rsquo;o\u00f9 je viens? O\u00f9 je vais?<br \/>\n\u00c0 quel bonheur suis-je appel\u00e9? Quel amour peut me faire vivre?<br \/>\nC&rsquo;est ce que traduisait le Deut\u00e9ronome <span style=\"font-size: small;\">(<strong>8<\/strong>,3)<\/span>:<br \/>\n<span style=\"color: #0000ff;\"><em>[Le Seigneur] t&rsquo;a fait avoir faim et Il t&rsquo;a donn\u00e9 la manne \u00e0 manger<br \/>\npour te faire reconna\u00eetre que l&rsquo;\u00eatre humain ne vit pas seulement de pain<br \/>\nmais qu&rsquo;il vit de tout ce qui sort de la bouche du Seigneur Dieu.<\/em><\/span><br \/>\nJ\u00e9sus reprendra ce passage du Deut\u00e9ronome dans le r\u00e9cit des tentations <span style=\"font-size: small;\">(Mt <strong>4<\/strong>,3-4)<\/span>:<br \/>\nLe tentateur s&rsquo;approcha et lui dit:<br \/>\n<span style=\"color: #0000ff;\"><em>\u00abSi tu es le Fils de Dieu, ordonne que ces pierres deviennent des pains.\u00bb<br \/>\nMais il r\u00e9pliqua: \u00abIl est \u00e9crit: Ce n&rsquo;est pas seulement de pain que l&rsquo;homme vivra,<br \/>\nmais de toute parole sortant de la bouche de Dieu.\u00bb<\/em><\/span><br \/>\nLe pain mat\u00e9riel est certes important et n\u00e9cessaire.<br \/>\nC&rsquo;est m\u00eame une injustice criante que d&rsquo;en priver certains<br \/>\nparce qu&rsquo;une minorit\u00e9 accumule et th\u00e9saurise \u00e0 son unique profit.<br \/>\nJ\u00e9sus -\u00e0 la suite des proph\u00e8tes- ne s&rsquo;est pas priv\u00e9 de le rappeler:<br \/>\n<span style=\"color: #0000ff;\"><em>Et il leur dit une parabole:<br \/>\n\u00abIl y avait un homme riche dont la terre avait bien rapport\u00e9.<br \/>\nEt il se demandait: Que vais-je faire? car je n&rsquo;ai pas o\u00f9 rassembler ma r\u00e9colte.<br \/>\nPuis il se dit: Voici ce que je vais faire: je vais d\u00e9molir mes greniers,<br \/>\nj&rsquo;en b\u00e2tirai de plus grands et j&rsquo;y rassemblerai tout mon bl\u00e9 et mes biens.<br \/>\nEt je me dirai \u00e0 moi-m\u00eame: Te voil\u00e0 avec quantit\u00e9 de biens en r\u00e9serve<br \/>\npour de longues ann\u00e9es; repose-toi, mange, bois, fais bombance.<br \/>\nMais Dieu lui dit: Insens\u00e9, cette nuit m\u00eame on te redemande ta vie,<br \/>\net ce que tu as pr\u00e9par\u00e9, qui donc l&rsquo;aura?<\/em><\/span>\u00a0\u00a0<span style=\"font-size: small;\">(Lc <strong>12<\/strong>,16-20)<\/span>.<br \/>\nPensons \u00e9galement \u00e0 la parabole du riche et du pauvre Lazare <span style=\"font-size: small;\">(cf. Lc <strong>16<\/strong>,19-31)<\/span>.<br \/>\n\u00c0 chaque si\u00e8cle, des proph\u00e8tes chr\u00e9tiens se l\u00e8veront pour d\u00e9noncer l&rsquo;injustice.<br \/>\nRappelons ces paroles tr\u00e8s fortes de l&rsquo;\u00e9v\u00eaque Basile au 4<span style=\"font-size: xx-small;\"><sup>e<\/sup><\/span> si\u00e8cle:<br \/>\n<span style=\"color: #990099;\">\u00abLes biens pr\u00e9sents, d&rsquo;o\u00f9 te sont-ils venus? Si tu dis: du hasard, tu es un ath\u00e9e<br \/>\ncar tu ne reconnais pas le Cr\u00e9ateur et tu ne sais pas gr\u00e9 \u00e0 celui qui t&rsquo;a pourvu.<br \/>\nSi tu confesses qu&rsquo;ils viennent de Dieu, dis-nous la raison pour laquelle tu les as re\u00e7us?<br \/>\nDieu serait-il injuste, lui qui nous partage in\u00e9galement les biens n\u00e9cessaires \u00e0 la vie?<br \/>\nPourquoi es-tu riche et celui-l\u00e0 pauvre?<br \/>\nToi qui enveloppes tous tes biens dans les plis d&rsquo;une insatiable avarice,<br \/>\ntu penses ne faire tort \u00e0 personne en d\u00e9pouillant tant de malheureux?<br \/>\nN&rsquo;es-tu pas un spoliateur, toi qui, de biens dont tu as re\u00e7u la gestion, fais ton bien propre?<br \/>\n\u00c0 l&rsquo;affam\u00e9 appartient le pain que tu mets en r\u00e9serve;<br \/>\n\u00e0 l&rsquo;homme nu le manteau que tu gardes dans tes coffres;<br \/>\nau va-nu-pieds, la sandale qui pourrit chez toi;<br \/>\nau besogneux, l&rsquo;argent que tu conserves enfoui.<br \/>\nAinsi tu commets autant d&rsquo;injustices qu&rsquo;il y a de gens<br \/>\n\u00e0 qui tu pourrais donner\u00bb<\/span> <span style=\"font-size: small;\"><em>(Hom. s.s. Luc 7)<\/em>.<\/span><br \/>\nMais le pain ne suffit pas pour nourrir la personne humaine.<br \/>\nIl faut aussi se nourrir de paroles qui donnent sens \u00e0 la vie,<br \/>\ncomme en t\u00e9moigne ce petit fait de vie br\u00e9silien.<br \/>\n<span style=\"color: #990099;\">\u00abLa famine \u00e9tait devenue extr\u00eame par une s\u00e9cheresse qui durait depuis des mois.<br \/>\nAu village deux enfants venaient de mourir de faim.<br \/>\n\u00c0 la messe du dimanche, l&rsquo;\u00c9vangile proclame:<br \/>\n<em>Ne vous inqui\u00e9tez pas de ce que vous mangerez.<\/em><br \/>\nAu moment de l&rsquo;hom\u00e9lie le pr\u00eatre reste muet.<br \/>\nC&rsquo;est alors qu&rsquo;un paysan l\u00e8ve la main pour dire:<br \/>\n\u00abHeureusement que nous sommes chr\u00e9tiens et que nous croyons \u00e0 cet \u00c9vangile:<br \/>\ncar autrement nous ne serions pas ici mais en train de nous d\u00e9chirer et de nous diviser<br \/>\npour accaparer le peu de vivres qui reste.<br \/>\nNous avons d\u00e9cid\u00e9s de rester unis et de tout partager.\u00bb<\/span><br \/>\nVoil\u00e0 ce que la foule du repas aurait d\u00fb voir:<br \/>\nla n\u00e9cessit\u00e9 de se nourrir de la <em>Tora<\/em>\u00a0\u00a0de Dieu, de son enseignement.<br \/>\nLe pain, comme la manne, signifie cette autre nourriture qu&rsquo;est la sagesse:<br \/>\n<span style=\"color: #0000ff;\"><em>La Sagesse a dress\u00e9 sa table et a cri\u00e9 son invitation:<br \/>\n\u00abVenez manger de mon pain et boire le vin que j&rsquo;ai pr\u00e9par\u00e9 pour vous\u00bb<\/em><\/span>\u00a0\u00a0<span style=\"font-size: small;\">(Pr <strong>9<\/strong>,1-5)<\/span>.<br \/>\nLes temps de la venue du messie \u00e9taient d\u00e9crits par les proph\u00e8tes<br \/>\ncomme des temps o\u00f9 la faim spirituelle serait raviv\u00e9e:<br \/>\n<span style=\"color: #0000ff;\"><em>Voici venir des jours o\u00f9 je r\u00e9pandrai la famine dans le pays,<br \/>\nnon pas la faim de pain, ni la soif d&rsquo;eau,<br \/>\nmais d&rsquo;entendre la Parole du Seigneur-Dieu<\/em><\/span>\u00a0\u00a0<span style=\"font-size: small;\">(Am <strong>8<\/strong>,11)<\/span>.<br \/>\nLe Cardinal Suhard a traduit cela en des paroles signifiantes:<br \/>\n<span style=\"color: #990099;\">\u00abL&rsquo;humain ne se rassasie pas seulement de pain,<br \/>\nni de bien-\u00eatre, ni de d\u00e9vouement, ni de tendresse:<br \/>\nde quelque nom qu&rsquo;il le d\u00e9signe, il est affam\u00e9 de Dieu\u00bb<\/span> <span style=\"font-size: small;\">(<em>Le sens de Dieu,<\/em> Lahure 1948, p. 23)<\/span>.<\/p>\n<p><span style=\"color: #0000ff;\"><em><strong>C&rsquo;est mon P\u00e8re qui vous donne le vrai pain du ciel.<\/strong><\/em><\/span><br \/>\nMais voir dans le repas des pains multipli\u00e9s le besoin de nourriture spirituelle,<br \/>\ny d\u00e9celer le signe d&rsquo;un pain du ciel,<br \/>\nce n&rsquo;est pas encore suffisant pour voir la vraie r\u00e9alit\u00e9 qui se vit avec J\u00e9sus.<br \/>\nJ\u00e9sus a fait passer la Samaritaine<br \/>\nde l&rsquo;eau de la Sagesse puis\u00e9e dans la <em>Tora<\/em><br \/>\n\u00e0 l&rsquo;eau vive qu&rsquo;on puise en communiant \u00e0 sa propre personne <span style=\"font-size: small;\">(Jn <strong>4<\/strong>,13-14)<\/span>:<br \/>\n<span style=\"color: #0000ff;\"><em>J\u00e9sus lui r\u00e9pondit: \u00abQuiconque boit de cette eau-ci aura encore soif;<br \/>\nmais celui qui boira de l&rsquo;eau que je lui donnerai n&rsquo;aura plus jamais soif;<br \/>\nau contraire, l&rsquo;eau que je lui donnerai deviendra en lui une source jaillissant en vie \u00e9ternelle\u00bb.<\/em><\/span><br \/>\nDe m\u00eame J\u00e9sus va faire d\u00e9couvrir que le pain de la parole de Dieu<br \/>\nne se trouve plus seulement dans la <em>Tora, <\/em><br \/>\nmais que c&rsquo;est sa personne tout enti\u00e8re qui r\u00e9v\u00e8le v\u00e9ritablement Dieu.<br \/>\nJ\u00e9sus est la <em>Tora<\/em> vivante, le vrai pain de Dieu:<br \/>\n<span style=\"color: #0000ff;\"><em>Celui qui descend du ciel est le pain de Dieu.<\/em><\/span><br \/>\nComme Mo\u00efse \u00e9tait \u00abmont\u00e9 au ciel pour en recevoir la <em>Tora\u00bb<\/em><br \/>\nainsi J\u00e9sus descend du ciel pour \u00eatre la <em>Tora<\/em> incarn\u00e9e, faite vie d&rsquo;homme.<br \/>\nUn targum (ps 68) interpr\u00e9tait en effet ainsi la mont\u00e9e de Mo\u00efse sur la montagne:<br \/>\n<span style=\"color: #990099;\">\u00abTu es mont\u00e9 au ciel&#8230; tu as appris la <em>Tora<\/em> et tu l&rsquo;as donn\u00e9e aux humains.\u00bb<\/span><br \/>\nLa diff\u00e9rence entre Mo\u00efse et J\u00e9sus est dans la relation qu&rsquo;ils ont chacun avec le P\u00e8re.<br \/>\nMo\u00efse est un grand proph\u00e8te certes mais J\u00e9sus est le fils parfait du P\u00e8re.<br \/>\nDans son prologue, Jean a d\u00e9j\u00e0 dit: <span style=\"color: #0000ff;\"><em>La Tora nous est donn\u00e9e par Mo\u00efse,<br \/>\nl&rsquo;amour qui est v\u00e9rit\u00e9 est venu par J\u00e9sus<\/em><\/span>\u00a0\u00a0<span style=\"font-size: small;\">(Jn <strong>1<\/strong>,17)<\/span>.<br \/>\nJ\u00e9sus ne cessera de proclamer son unit\u00e9 avec le P\u00e8re <span style=\"font-size: small;\">(Jn <strong>7<\/strong>,16)<\/span>:<br \/>\n<span style=\"color: #0000ff;\"><em>Mon enseignement ne vient pas de moi mais de mon P\u00e8re qui m&rsquo;envoie.<\/em><\/span><br \/>\nJ\u00e9sus est le fils parfait qui r\u00e9p\u00e8te parfaitement les paroles du P\u00e8re.<br \/>\nEt il ne s&rsquo;agit plus seulement d&rsquo;un enseignement qui est donn\u00e9,<br \/>\nmais d&rsquo;une personne qui se donne:<br \/>\n<span style=\"color: #0000ff;\"><em>Si vous retenez mes pr\u00e9ceptes, vous demeurerez dans mon amour<\/em><\/span>\u00a0\u00a0<span style=\"font-size: small;\">(Jn <strong>15<\/strong>,10)<\/span>.<br \/>\nLa communication aboutit \u00e0 une communion personnelle avec l&rsquo;Enseigneur <span style=\"font-size: small;\">(Jn <strong>15<\/strong>,15)<\/span>:<br \/>\n<span style=\"color: #0000ff;\"><em>Je vous appelle amis parce que tout ce que j&rsquo;ai appris de mon P\u00e8re je vous l&rsquo;ai fait conna\u00eetre.<\/em><\/span><br \/>\nLa connaissance aboutit \u00e0 l&rsquo;unit\u00e9 dans l&rsquo;amour. L&rsquo;ap\u00f4tre Paul dira:<br \/>\n<span style=\"color: #0000ff;\"><em>Ce n&rsquo;est plus moi qui vis, c&rsquo;est l&rsquo;Enseigneur qui vit en moi<\/em><\/span>\u00a0\u00a0<span style=\"font-size: small;\">(Ga <strong>2<\/strong>,20)<\/span>.<br \/>\nSi Mo\u00efse avait indiqu\u00e9 dans la <em>Tora<\/em> des actions \u00e0 faire pour \u00eatre fid\u00e8les \u00e0 Dieu,<br \/>\nl&rsquo;unique action d\u00e9sormais est la communion au Fils envoy\u00e9 par le P\u00e8re:<br \/>\n<span style=\"color: #0000ff;\"><em>Voici l&rsquo;action de Dieu: croire en celui-l\u00e0 qu&rsquo;Il a envoy\u00e9.<\/em><\/span><br \/>\nCroire a ici le sens fort de mettre toute sa confiance en quelqu&rsquo;un,<br \/>\nde s&rsquo;engager comme disciple d&rsquo;un ma\u00eetre de vie.<br \/>\nIl ne s&rsquo;agit pas seulement que croire que J\u00e9sus vient de Dieu<br \/>\nmais de croire <em>en<\/em> lui, de miser toute sa vie sur lui.<br \/>\nPaul dira qu&rsquo;il a tout sacrifi\u00e9 pour gagner le bien supr\u00eame:<br \/>\nconna\u00eetre J\u00e9sus: lui et la puissance de la r\u00e9surrection <span style=\"font-size: small;\">(cf. Ph <strong>3<\/strong>,7-11)<\/span>.<br \/>\nEt parce qu&rsquo;on a mis sa foi en J\u00e9sus, alors on devient comme lui:<br \/>\non vit de lui, on communie \u00e0 sa pens\u00e9e, on agit selon son esprit.<br \/>\nIl ne s&rsquo;agit pas seulement de croire que les paroles de J\u00e9sus sont v\u00e9rit\u00e9,<br \/>\nmais de croire en lui pour \u00eatre en communion avec lui.<br \/>\nEt se nourrir de J\u00e9sus, c&rsquo;est \u00eatre nourri d&rsquo;un pain qui demeure<br \/>\ncar J\u00e9sus a en lui cette vie \u00e9ternelle par sa communion ind\u00e9fectible avec le P\u00e8re qui est Dieu.<br \/>\n\u00catre branch\u00e9 sur J\u00e9sus, \u00eatre li\u00e9 \u00e0 lui,<br \/>\nc&rsquo;est donc \u00eatre en communion pour toujours avec le P\u00e8re.<br \/>\nC&rsquo;est ne plus \u00eatre affam\u00e9 \u00e0 jamais.<br \/>\n\u00c0 la suite de cet entretien de la synagogue de Capharna\u00fcm, Pierre dira \u00e0 J\u00e9sus:<br \/>\n<span style=\"color: #0000ff;\"><em>\u00c0 qui irions, tu as des paroles de vie \u00e9ternelle<\/em><\/span>\u00a0\u00a0<span style=\"font-size: small;\">(Jn <strong>6<\/strong>,68)<\/span>.<\/p>\n<p><span style=\"color: #0000ff;\"><strong><em>Seigneur, donne-nous toujours de ce pain!<\/em><\/strong><\/span><br \/>\nVoil\u00e0 sans doute le cri qui peut jaillir de nos l\u00e8vres, de notre coeur.<br \/>\nComment vivre de l&rsquo;esprit m\u00eame de J\u00e9sus pour vivre de Dieu \u00e9ternellement?<br \/>\nQue nous faut-il faire?, dirions-nous \u00e0 la suite des Juifs de Capharna\u00fcm.<br \/>\nIl nous faut fr\u00e9quenter J\u00e9sus comme l&rsquo;amant fr\u00e9quente sa bien-aim\u00e9e.<br \/>\nEt pour cela il ne suffit pas d&rsquo;\u00e9motions -aussi belles soient-elles,<br \/>\nil faut nourrir notre coeur-m\u00e9moire des paroles de J\u00e9sus<br \/>\npour qu&rsquo;elles deviennent notre agir quotidien. Croire en J\u00e9sus, c&rsquo;est \u00ab\u00a0agir ses paroles\u00a0\u00bb.<br \/>\nEt pour \u00ab\u00a0agir ses paroles\u00a0\u00bb, il faut qu&rsquo;elles soient imprim\u00e9es dans notre m\u00e9moire;<br \/>\ntout autant qu&rsquo;y est imprim\u00e9 l&rsquo;agir du manger, du boire, du parler.<br \/>\nLa \u00ab\u00a0manducation\u00a0\u00bb des paroles de J\u00e9sus doit \u00eatre aussi quotidienne<br \/>\nque la manducation du pain.<br \/>\nOr se nourrir est un besoin quotidien, plusieurs fois r\u00e9p\u00e9t\u00e9 au long du jour.<br \/>\nComme on prend et mange le pain de chaque jour,<br \/>\nil faut prendre et apprendre la parole de l&rsquo;\u00c9vangile, celle du Jour-qui-vient.<br \/>\nIl est bon de l&rsquo;\u00e9couter (la lire \u00e0 haute voix) le soir<br \/>\npour qu&rsquo;elle meuble la m\u00e9moire inconsciente de notre sommeil.<br \/>\nIl faut se la redire et la m\u00e9diter longuement au r\u00e9veil:<br \/>\n<span style=\"color: #0000ff;\"><em>Je te cherche d\u00e8s l&rsquo;aurore, ma gorge a soif de ta parole,<\/em><\/span>\u00a0\u00a0dit le psaume <span style=\"font-size: small;\">(<strong>63<\/strong>,1)<\/span>.<br \/>\nLe chant souvent aide \u00e0 mieux m\u00e9moriser la parole.<br \/>\nLes courts refrains des chants de Taiz\u00e9, parce qu&rsquo;ils sont longuement r\u00e9p\u00e9t\u00e9s,<br \/>\ns&rsquo;impriment dans le coeur-m\u00e9moire. La vraie m\u00e9moire de la parole<br \/>\nest compr\u00e9hension par le dedans, attention, approfondissement.<br \/>\nAlors, chaque fois que la parole, jaillie de notre m\u00e9moire, dictera notre conduite,<br \/>\ncette parole s&rsquo;enrichira de tout l&rsquo;apport de la vie.<br \/>\nC&rsquo;est ainsi que se sont forg\u00e9s -au long des \u00e2ges- les proverbes,<br \/>\nm\u00e9moires collectives de sagesse de vie.<br \/>\nMadeleine Delbr\u00eal traduit merveilleusement comment la Parole nous nourrit:<br \/>\n<span style=\"color: #990099;\">La phrase du Seigneur que nous avons arrach\u00e9e \u00e0 l&rsquo;\u00c9vangile, elle ne doit plus nous quitter&#8230;<br \/>\nElle veut f\u00e9conder, modifier, renouveler la poign\u00e9e de main que nous aurons \u00e0 donner,<br \/>\nnotre effort sur notre t\u00e2che, notre regard sur ceux que nous rencontrons, notre r\u00e9action<br \/>\nsur la fatigue, notre sursaut devant la douleur, notre \u00e9panouissement dans la joie<\/span><br \/>\n<span style=\"font-size: small;\">(cit\u00e9 dans J. Loew, <em>Vivre l&rsquo;\u00c9vangile selon M. Delbr\u00eal,<\/em> Centurion 1994, p. 99)<\/span>.<br \/>\nIl nous faut \u00eatre non pas l&rsquo;appreneur passager mais l&rsquo;appreneur fid\u00e8le de J\u00e9sus.<br \/>\nL&rsquo;appreneur passager est comme le riche qui s&rsquo;\u00e9merveille des paroles de Dieu<br \/>\nmais reste encombr\u00e9 d&rsquo;autres paroles qui l&#8217;emp\u00eachent de vivre \u00e0 fond selon l&rsquo;\u00c9vangile.<br \/>\nL&rsquo;appreneur fid\u00e8le conna\u00eet avec exactitude,<br \/>\nmais surtout vit fid\u00e8lement selon les paroles de l&rsquo;Enseigneur.<br \/>\nIl vit \u00e0 la mani\u00e8re de l&rsquo;Enseigneur, plus encore il laisse vivre en lui l&rsquo;Enseigneur.<br \/>\nMaurice Zundel traduisait ainsi cette n\u00e9cessit\u00e9 de vivre le Christ:<br \/>\n<span style=\"color: #990099;\">\u00abTous les \u00e9vangiles seront absolument vains et ne seront que des ferments d&rsquo;idol\u00e2trie,<br \/>\nsi nous ne devenons pas finalement nous-m\u00eames l&rsquo;\u00c9vangile,<br \/>\nsi l&rsquo;\u00c9vangile ne passe pas par nos mains,<br \/>\nsi nos mains ne deviennent pas des mains de lumi\u00e8re,<br \/>\ndes mains qui donnent et ne veulent plus poss\u00e9der,<br \/>\nsi notre visage ne porte pas le visage de la divine bont\u00e9&#8230;\u00bb<\/span><br \/>\nCela est l&rsquo;oeuvre de toute la vie.<br \/>\nPendant 40 ann\u00e9es de solitude au d\u00e9sert,<br \/>\nles H\u00e9breux ont v\u00e9cu du pain tomb\u00e9 des cieux et de la <em>Tora<\/em> descendue des cieux.<br \/>\nPendant toute sa vie, dans la solitude de la pri\u00e8re,<br \/>\nle chr\u00e9tien se nourrit du pain de vie qu&rsquo;est le Fils<br \/>\net de son \u00c9vangile qui vient du P\u00e8re des cieux.<br \/>\nEn go\u00fbtant l&rsquo;\u00c9vangile, il apprend \u00e0 conna\u00eetre et go\u00fbter l&rsquo;Enseigneur.<br \/>\n<span style=\"color: #990099;\">L&rsquo;\u00c9vangile est non seulement le livre du Seigneur vivant, mais le livre du Seigneur \u00e0 vivre.<br \/>\nIl n&rsquo;est pas fait pour \u00eatre lu mais pour \u00eatre re\u00e7u en nous.<br \/>\nL&rsquo;\u00c9vangile n&rsquo;est pas un livre comme les autres. Il est comme un rendez-vous<br \/>\nque le Christ donne \u00e0 chacun d&rsquo;entre nous avec lui&#8230; un rendez-vous de personne \u00e0 personne,<br \/>\nun coeur-\u00e0-coeur vrai, intime, concret<\/span><br \/>\n(Madeleine Delbr\u00eal, cit\u00e9 dans J. Loew, <em>Vivre l&rsquo;\u00c9vangile, Centurion,<\/em> p. 99).<br \/>\nIl ne peut y avoir de rencontre, de connaissance intime de J\u00e9sus<br \/>\npour nous aujourd&rsquo;hui -deux mille ans apr\u00e8s Nazareth et la Croix-,<br \/>\nsans ce recours obstin\u00e9 et permanent \u00e0 l&rsquo;\u00c9vangile<br \/>\nlu, m\u00e9dit\u00e9, pri\u00e9, pour \u00eatre v\u00e9cu chaque jour.<br \/>\nN&rsquo;est-ce pas cela que J\u00e9sus lui-m\u00eame nous a fait demander au P\u00e8re:<br \/>\n<em>\u00ab<span style=\"color: #0000ff;\">Donne-nous chaque jour le pain du Jour qui vient,<\/span><\/em> le pain de l&rsquo;\u00e9ternelle vie.<br \/>\nOh, oui, Seigneur, fais-nous vivre de ce pain, pour tou-jours!\u00bb<\/p>\n<p align=\"right\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: small;\"><strong><span style=\"color: #990000;\">Georges Convert<\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<h5>\u00bb\u00bb\u00bb Questions<\/h5>\n<p>1.\u00a0Dans quel contexte se situe l&rsquo;hom\u00e9lie de J\u00e9sus dans la synagogue de Capharna\u00fcm?<br \/>\n2.\u00a0Quel sens a le signe de la manne pour les contemporains de J\u00e9sus?<br \/>\n3.\u00a0Que signifie le \u00abpain qui vient de Dieu\u00bb?<br \/>\n4.\u00a0Comment actualiser les paroles de l&rsquo;\u00c9v\u00eaque Basile?<br \/>\n5. De quelle mani\u00e8re pouvons-nous nourrir de l&rsquo;\u00c9vangile?<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>18e dimanche ordinaire\u00a0(ann\u00e9e B), selon l&rsquo;\u00e9crit de Jean\u00a06, 24-35 24 Quand la foule voit que J\u00e9sus n&rsquo;est pas l\u00e0, ni ses disciples, ils montent dans les barques et vont \u00e0 Capharna\u00fcm chercher J\u00e9sus. 25 L&rsquo;ayant trouv\u00e9 de l&rsquo;autre c\u00f4t\u00e9 de &hellip; <a href=\"https:\/\/relaismontroyal.org\/wp\/evangile-du-dimanche-5-aout-2018\/\">Lire la suite\u00ad\u00ad<\/a><\/p>\n","protected":false},"author":2,"featured_media":160,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,16],"tags":[287,49,47,50,25,42,288],"class_list":["post-189985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activites-spirituelles","category-du-pain-sur-la-table","tag-18e-dimanche-ordinaire","tag-commentaire","tag-dimanche","tag-du-pain-sur-la-table-2","tag-evangile","tag-evangiles","tag-jean-6-24-35"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/relaismontroyal.org\/wp\/wp-content\/uploads\/2014\/02\/IMG_5175.jpg?fit=3282%2C646&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/relaismontroyal.org\/wp\/wp-json\/wp\/v2\/posts\/189985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/relaismontroyal.org\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/relaismontroyal.org\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/relaismontroyal.org\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/relaismontroyal.org\/wp\/wp-json\/wp\/v2\/comments?post=189985"}],"version-history":[{"count":1,"href":"https:\/\/relaismontroyal.org\/wp\/wp-json\/wp\/v2\/posts\/189985\/revisions"}],"predecessor-version":[{"id":189986,"href":"https:\/\/relaismontroyal.org\/wp\/wp-json\/wp\/v2\/posts\/189985\/revisions\/189986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/relaismontroyal.org\/wp\/wp-json\/wp\/v2\/media\/160"}],"wp:attachment":[{"href":"https:\/\/relaismontroyal.org\/wp\/wp-json\/wp\/v2\/media?parent=189985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/relaismontroyal.org\/wp\/wp-json\/wp\/v2\/categories?post=189985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/relaismontroyal.org\/wp\/wp-json\/wp\/v2\/tags?post=189985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}